{"id":963,"date":"2022-05-23T21:07:18","date_gmt":"2022-05-24T00:07:18","guid":{"rendered":"https:\/\/kifase.com.br\/a\/?post_type=product&#038;p=963"},"modified":"2022-05-23T21:09:20","modified_gmt":"2022-05-24T00:09:20","slug":"dps-steck","status":"publish","type":"product","link":"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/","title":{"rendered":"DPS Steck"},"content":{"rendered":"<p>Aplica\u00e7\u00e3o<br \/>\nOs Dispositivos de Prote\u00e7\u00e3o contra Surtos (DPS) s\u00e3o utilizados nas instala\u00e7\u00f5es el\u00e9tricas para protegerem os equipamentos el\u00e9tricos e eletr\u00f4nicos contra sobrecargas geradas por descargas atmosf\u00e9ricas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Aplica\u00e7\u00e3o<\/strong><br \/>\nOs Dispositivos de Prote\u00e7\u00e3o contra Surtos (DPS) s\u00e3o utilizados nas instala\u00e7\u00f5es el\u00e9tricas para protegerem os equipamentos el\u00e9tricos e eletr\u00f4nicos contra sobrecargas geradas por descargas atmosf\u00e9ricas.<\/p>\n<p><strong>Caracter\u00edsticas<\/strong><\/p>\n<ul>\n<li>Corrente Nominal: 10kA;<\/li>\n<li>Corrente M\u00e1xima: 20kA;<\/li>\n<li>Tempo de resposta &lt; 25ns;<\/li>\n<li>Grau de Prote\u00e7\u00e3o: IP20;<\/li>\n<li>Atende a IEC 61643;<\/li>\n<li>Material: caixa termopl\u00e1stica antichama;<\/li>\n<li>Temperatura de aplica\u00e7\u00e3o: -40\u00b0C &#8211; +80\u00b0C;<\/li>\n<li>Tens\u00e3o de opera\u00e7\u00e3o: 275V;<\/li>\n<li>Sinaliza\u00e7\u00e3o: verde (perfeito estado) \/ vermelho (substituir).<\/li>\n<\/ul>\n","protected":false},"featured_media":964,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[26,45],"product_tag":[],"class_list":["post-963","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-disjuntor-contador-mini-contador","product_cat-drs-e-dps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>DPS Steck - Kifase Materiais El\u00e9tricos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DPS Steck - Kifase Materiais El\u00e9tricos\" \/>\n<meta property=\"og:description\" content=\"Aplica\u00e7\u00e3o Os Dispositivos de Prote\u00e7\u00e3o contra Surtos (DPS) s\u00e3o utilizados nas instala\u00e7\u00f5es el\u00e9tricas para protegerem os equipamentos el\u00e9tricos e eletr\u00f4nicos contra sobrecargas geradas por descargas atmosf\u00e9ricas.  Caracter\u00edsticas   Corrente Nominal: 10kA;  Corrente M\u00e1xima: 20kA;  Tempo de resposta &lt; 25ns;  Grau de Prote\u00e7\u00e3o: IP20;  Atende a IEC 61643;  Material: caixa termopl\u00e1stica antichama;  Temperatura de aplica\u00e7\u00e3o: -40\u00b0C - +80\u00b0C;  Tens\u00e3o de opera\u00e7\u00e3o: 275V;  Sinaliza\u00e7\u00e3o: verde (perfeito estado) \/ vermelho (substituir).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/\" \/>\n<meta property=\"og:site_name\" content=\"Kifase Materiais El\u00e9tricos\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kifaseloja\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-24T00:09:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kifase.com.br\/a\/wp-content\/uploads\/2022\/05\/dps-steck.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"827\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/\",\"url\":\"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/\",\"name\":\"DPS Steck - Kifase Materiais El\u00e9tricos\",\"isPartOf\":{\"@id\":\"https:\/\/kifase.com.br\/a\/#website\"},\"datePublished\":\"2022-05-24T00:07:18+00:00\",\"dateModified\":\"2022-05-24T00:09:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/kifase.com.br\/a\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\/\/kifase.com.br\/a\/loja\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DPS Steck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kifase.com.br\/a\/#website\",\"url\":\"https:\/\/kifase.com.br\/a\/\",\"name\":\"Kifase Materiais El\u00e9tricos\",\"description\":\"Materiais el\u00e9tricos, ilumina\u00e7\u00e3o, ferramentas e utilidades.\",\"publisher\":{\"@id\":\"https:\/\/kifase.com.br\/a\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kifase.com.br\/a\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/kifase.com.br\/a\/#organization\",\"name\":\"Kifase Materiais El\u00e9tricos\",\"url\":\"https:\/\/kifase.com.br\/a\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/kifase.com.br\/a\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/kifase.com.br\/a\/wp-content\/uploads\/2022\/03\/kisafe-.jpg\",\"contentUrl\":\"https:\/\/kifase.com.br\/a\/wp-content\/uploads\/2022\/03\/kisafe-.jpg\",\"width\":339,\"height\":105,\"caption\":\"Kifase Materiais El\u00e9tricos\"},\"image\":{\"@id\":\"https:\/\/kifase.com.br\/a\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/kifaseloja\",\"https:\/\/www.instagram.com\/kifasemat.e\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DPS Steck - Kifase Materiais El\u00e9tricos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/","og_locale":"pt_BR","og_type":"article","og_title":"DPS Steck - Kifase Materiais El\u00e9tricos","og_description":"Aplica\u00e7\u00e3o Os Dispositivos de Prote\u00e7\u00e3o contra Surtos (DPS) s\u00e3o utilizados nas instala\u00e7\u00f5es el\u00e9tricas para protegerem os equipamentos el\u00e9tricos e eletr\u00f4nicos contra sobrecargas geradas por descargas atmosf\u00e9ricas.  Caracter\u00edsticas   Corrente Nominal: 10kA;  Corrente M\u00e1xima: 20kA;  Tempo de resposta &lt; 25ns;  Grau de Prote\u00e7\u00e3o: IP20;  Atende a IEC 61643;  Material: caixa termopl\u00e1stica antichama;  Temperatura de aplica\u00e7\u00e3o: -40\u00b0C - +80\u00b0C;  Tens\u00e3o de opera\u00e7\u00e3o: 275V;  Sinaliza\u00e7\u00e3o: verde (perfeito estado) \/ vermelho (substituir).","og_url":"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/","og_site_name":"Kifase Materiais El\u00e9tricos","article_publisher":"https:\/\/www.facebook.com\/kifaseloja","article_modified_time":"2022-05-24T00:09:20+00:00","og_image":[{"width":827,"height":827,"url":"https:\/\/kifase.com.br\/a\/wp-content\/uploads\/2022\/05\/dps-steck.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/","url":"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/","name":"DPS Steck - Kifase Materiais El\u00e9tricos","isPartOf":{"@id":"https:\/\/kifase.com.br\/a\/#website"},"datePublished":"2022-05-24T00:07:18+00:00","dateModified":"2022-05-24T00:09:20+00:00","breadcrumb":{"@id":"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kifase.com.br\/a\/produto\/dps-steck\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kifase.com.br\/a\/produto\/dps-steck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/kifase.com.br\/a\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/kifase.com.br\/a\/loja\/"},{"@type":"ListItem","position":3,"name":"DPS Steck"}]},{"@type":"WebSite","@id":"https:\/\/kifase.com.br\/a\/#website","url":"https:\/\/kifase.com.br\/a\/","name":"Kifase Materiais El\u00e9tricos","description":"Materiais el\u00e9tricos, ilumina\u00e7\u00e3o, ferramentas e utilidades.","publisher":{"@id":"https:\/\/kifase.com.br\/a\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kifase.com.br\/a\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/kifase.com.br\/a\/#organization","name":"Kifase Materiais El\u00e9tricos","url":"https:\/\/kifase.com.br\/a\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/kifase.com.br\/a\/#\/schema\/logo\/image\/","url":"https:\/\/kifase.com.br\/a\/wp-content\/uploads\/2022\/03\/kisafe-.jpg","contentUrl":"https:\/\/kifase.com.br\/a\/wp-content\/uploads\/2022\/03\/kisafe-.jpg","width":339,"height":105,"caption":"Kifase Materiais El\u00e9tricos"},"image":{"@id":"https:\/\/kifase.com.br\/a\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kifaseloja","https:\/\/www.instagram.com\/kifasemat.e"]}]}},"_links":{"self":[{"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/product\/963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/comments?post=963"}],"version-history":[{"count":1,"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/product\/963\/revisions"}],"predecessor-version":[{"id":965,"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/product\/963\/revisions\/965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/media\/964"}],"wp:attachment":[{"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/media?parent=963"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/product_cat?post=963"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kifase.com.br\/a\/wp-json\/wp\/v2\/product_tag?post=963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}